{"id":3685,"date":"2024-07-12T09:35:43","date_gmt":"2024-07-12T07:35:43","guid":{"rendered":"https:\/\/www.ing-solvan.com\/?post_type=product&#038;p=3685"},"modified":"2024-11-29T13:33:55","modified_gmt":"2024-11-29T12:33:55","slug":"papel-de-enmascarar-kraft","status":"publish","type":"product","link":"https:\/\/www.ing-solvan.com\/en\/producto\/papel-de-enmascarar-kraft\/","title":{"rendered":"PAPEL DE ENMASCARAR KRAFT"},"content":{"rendered":"<div class=\"wprt-container\">\n<div class=\"table-responsive\">\n<div class=\"table-responsive wprt_style_display\">\n<table class=\"table\">\n<thead>\n<tr>\n<td style=\"text-align: center\"><strong>REFERENCIA<\/strong><\/td>\n<td style=\"text-align: center\"><strong>DESCRIPCI\u00d3N<\/strong><\/td>\n<td style=\"text-align: center\"><strong>MEDIDAS<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td style=\"text-align: center\">2001-001860<\/td>\n<td style=\"text-align: center\">40 G<\/td>\n<td style=\"text-align: center\">45 cm x 300 m<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center\">2001-001870<\/td>\n<td style=\"text-align: center\">40 G<\/td>\n<td style=\"text-align: center\">60 cm x 300 m<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center\">2001-001880<\/td>\n<td style=\"text-align: center\">40 G<\/td>\n<td style=\"text-align: center\">90 cm x 300 m<\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center\">2001-001890<\/td>\n<td style=\"text-align: center\">40 G<\/td>\n<td style=\"text-align: center\">120 cm x 300 m<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Papel de enmascarar de 40 g\/m2 y 300 m de largo, tratado para impedir el traspaso de pintura o barniz.<\/p>\n<p>Se suministra en bolsa individual en todas las medidas. Peso: 40 g\/m2.<\/p>\n","protected":false},"featured_media":3691,"comment_status":"closed","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[97,94],"product_tag":[],"class_list":{"0":"post-3685","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-papel-de-enmascarar","7":"product_cat-sistemas-de-emascarado-y-proteccion","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/product\/3685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/comments?post=3685"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/media\/3691"}],"wp:attachment":[{"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/media?parent=3685"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/product_brand?post=3685"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/product_cat?post=3685"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.ing-solvan.com\/en\/wp-json\/wp\/v2\/product_tag?post=3685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}